{"id":30,"date":"2022-08-15T02:41:07","date_gmt":"2022-08-15T02:41:07","guid":{"rendered":"https:\/\/ovatheme.com\/romancy\/?page_id=30"},"modified":"2023-07-25T16:19:10","modified_gmt":"2023-07-25T16:19:10","slug":"room-listing-3","status":"publish","type":"page","link":"https:\/\/kingscourtyardvumba.com\/index.php\/room-listing-3\/","title":{"rendered":"Room Listing 3"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"30\" class=\"elementor elementor-30\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7018899 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7018899\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f37e49c\" data-id=\"f37e49c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb1a62d elementor-widget elementor-widget-ovabrw_search_ajax\" data-id=\"eb1a62d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ovabrw_search_ajax.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<div class=\"ovabrw-search-ajax\">\n\t<div class=\"wrap-search-ajax wrap-search-ajax-template3\" data-template=\"template3\">\n\t\t\n\t\t<!-- Search -->\n\t\t\n<div class=\"ovabrw-search\">\n\n\t<form action=\"https:\/\/kingscourtyardvumba.com\" method=\"POST\" class=\"ovabrw-search-form\">\n\n\t\t<div class=\"ovabrw-s-field\">\n\n\t\t\t<div class=\"search-field\">\n\t\t\t\t<div class=\"ovabrw-label\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-calendar\"><\/i>\t\t\t\t\t<span class=\"label\">Check in<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"ovabrw-input\">\n\t\t\t\t\t<input \n\t\t\t\t\t\ttype=\"text\" \n\t\t\t\t\t\tname=\"ovabrw_pickup_date\" \n\t\t\t\t\t\tvalue=\"\"\n\t\t\t\t\t\tclass=\"ovabrw_datetimepicker ovabrw_start_date\" \n\t\t\t\t\t\tplaceholder=\"dd-mm-yyyy\" \n\t\t\t\t\t\tautocomplete=\"off\" \n\t\t\t\t\t\tdata-hour_default=\"07:00\" \n\t\t\t\t\t\tdata-time_step=\"30\" \n\t\t\t\t\t\tdata-dateformat=\"d-m-Y\" \n\t\t\t\t\t\tonkeydown=\"return false\" \n\t\t\t\t\t\tonfocus=\"blur();\" \/>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"search-field\">\n\t\t\t\t<div class=\"ovabrw-label\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-calendar\"><\/i>\t\t\t\t\t<span class=\"label\">Check out<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"ovabrw-input\">\n\t\t\t\t\t<input \n\t\t\t\t\t\ttype=\"text\" \n\t\t\t\t\t\tname=\"ovabrw_pickoff_date\"\n\t\t\t\t\t\tvalue=\"\"\n\t\t\t\t\t\tclass=\"ovabrw_datetimepicker ovabrw_end_date\" \n\t\t\t\t\t\tplaceholder=\"dd-mm-yyyy\" \n\t\t\t\t\t\tautocomplete=\"off\" \n\t\t\t\t\t\tdata-hour_default=\"07:00\" \n\t\t\t\t\t\tdata-time_step=\"30\" \n\t\t\t\t\t\tdata-dateformat=\"d-m-Y\" \n\t\t\t\t\t\tonkeydown=\"return false\" \n\t\t\t\t\t\tonfocus=\"blur();\" \/>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"search-field guestspicker-control\">\n\t\t\t\t<div class=\"ovabrw-label\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-user-group\"><\/i>\t\t\t\t\t<span class=\"label\">Guests<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"ovabrw-guestspicker\">\n\t\t\t\t\t<div class=\"guestspicker\">\n\t\t\t\t\t\t<span class=\"gueststotal\">2<\/span>\n\t\t\t\t\t\t<span class=\"guestslabel\">Persons<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"ovabrw-guestspicker-content\">\n\t\t\t\t\t<div class=\"guests-buttons\">\n\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t<label>Adults<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"guests-button\">\n\t\t\t\t\t\t\t<div class=\"guests-icon minus\">\n\t\t\t\t\t\t\t\t<i class=\"ovaicon ovaicon-minus\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<input \n\t\t\t\t\t\t\t\ttype=\"text\" \n\t\t\t\t\t\t\t\tid=\"ovabrw_adults\" \n\t\t\t\t\t\t\t\tname=\"ovabrw_adults\" \n\t\t\t\t\t\t\t\tclass=\"ovabrw_adults\" \n\t\t\t\t\t\t\t\tvalue=\"2\" \n\t\t\t\t\t\t\t\tmin=\"1\" \n\t\t\t\t\t\t\t\tmax=\"5\" \/>\n\t\t\t\t\t\t\t<div class=\"guests-icon plus\">\n\t\t\t\t\t\t\t\t<i class=\"ovaicon ovaicon-plus\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"guests-buttons\">\n\t\t\t\t\t\t<div class=\"description\">\n\t\t\t\t\t\t\t<label>Childrens<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"guests-button\">\n\t\t\t\t\t\t\t<div class=\"guests-icon minus\">\n\t\t\t\t\t\t\t\t<i class=\"ovaicon ovaicon-minus\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<input \n\t\t\t\t\t\t\t\ttype=\"text\" \n\t\t\t\t\t\t\t\tid=\"ovabrw_childrens\" \n\t\t\t\t\t\t\t\tname=\"ovabrw_childrens\" \n\t\t\t\t\t\t\t\tclass=\"ovabrw_childrens\" \n\t\t\t\t\t\t\t\tvalue=\"0\" \n\t\t\t\t\t\t\t\tmin=\"0\" \n\t\t\t\t\t\t\t\tmax=\"4\" \/>\n\t\t\t\t\t\t\t<div class=\"guests-icon plus\">\n\t\t\t\t\t\t\t\t<i class=\"ovaicon ovaicon-plus\"><\/i>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"search-field beds-control\">\n\t\t\t\t<div class=\"ovabrw-label\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-bed\"><\/i>\t\t\t\t\t<span class=\"label\">Beds<\/span>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"guests-button beds-button\">\n\t\t\t\t\t<div class=\"guests-icon minus\">\n\t\t\t\t\t\t<i class=\"ovaicon ovaicon-minus\"><\/i>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<input \n\t\t\t\t\t\ttype=\"text\" \n\t\t\t\t\t\tid=\"ovabrw_beds\" \n\t\t\t\t\t\tname=\"ovabrw_beds\" \n\t\t\t\t\t\tclass=\"ovabrw_beds\" \n\t\t\t\t\t\tvalue=\"1\" \n\t\t\t\t\t\tmin=\"1\" \n\t\t\t\t\t\tmax=\"5\" \/>\n\t\t\t\t\t<div class=\"guests-icon plus\">\n\t\t\t\t\t\t<i class=\"ovaicon ovaicon-plus\"><\/i>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"search-field baths-control\">\n\t\t\t\t<div class=\"ovabrw-label\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"icomoon icomoon-bathtub\"><\/i>\t\t\t\t\t<span class=\"label\">Baths<\/span>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"guests-button baths-button\">\n\t\t\t\t\t<div class=\"guests-icon minus\">\n\t\t\t\t\t\t<i class=\"ovaicon ovaicon-minus\"><\/i>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<input \n\t\t\t\t\t\ttype=\"text\" \n\t\t\t\t\t\tid=\"ovabrw_baths\" \n\t\t\t\t\t\tname=\"ovabrw_baths\" \n\t\t\t\t\t\tclass=\"ovabrw_baths\" \n\t\t\t\t\t\tvalue=\"1\" \n\t\t\t\t\t\tmin=\"1\" \n\t\t\t\t\t\tmax=\"3\" \/>\n\t\t\t\t\t<div class=\"guests-icon plus\">\n\t\t\t\t\t\t<i class=\"ovaicon ovaicon-plus\"><\/i>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t\t<div class=\"ovabrw-search-btn\">\n\t\t\t\t\t\t<button class=\"ovabrw-btn\" type=\"submit\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"ovaicon ovaicon-search\"><\/i>Search\t\t\t<\/button>\n\t\t<\/div>\n\n\t<\/form>\n\t\n<\/div>\n\t\t<!-- Load more -->\n\t\t<div class=\"wrap-load-more\" style=\"display: none;\">\n\t\t\t<svg class=\"loader\" width=\"50\" height=\"50\">\n\t\t\t\t<circle cx=\"25\" cy=\"25\" r=\"10\" \/>\n\t\t\t\t<circle cx=\"25\" cy=\"25\" r=\"20\" \/>\n\t\t\t<\/svg>\n\t\t<\/div>\n\n\t\t<!-- Search result -->\n\t\t<div \n\t\t\tid=\"search-ajax-result\" \n\t\t\tclass=\"search-ajax-result\" \n\t\t\tdata-order=\"DESC\" \n\t\t\tdata-orderby=\"date\" \n\t\t\tdata-posts-per-page=\"5\">\n\t\t<\/div>\n\n\t\t<!-- Video -->\n\t\t<div class=\"modal-container\">\n\t\t\t<div class=\"modal\">\n\t\t\t\t<div class=\"modal-close\">\n\t\t\t\t\t<i class=\"ovaicon-cancel\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<iframe class=\"modal-video\" allow=\"autoplay\"><\/iframe>\n\t\t\t<\/div>\n\t\t<\/div>\n\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Check in Check out Guests 2 Persons Adults Childrens Beds Baths Search<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-30","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kingscourtyardvumba.com\/index.php\/wp-json\/wp\/v2\/pages\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kingscourtyardvumba.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kingscourtyardvumba.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kingscourtyardvumba.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kingscourtyardvumba.com\/index.php\/wp-json\/wp\/v2\/comments?post=30"}],"version-history":[{"count":1,"href":"https:\/\/kingscourtyardvumba.com\/index.php\/wp-json\/wp\/v2\/pages\/30\/revisions"}],"predecessor-version":[{"id":3917,"href":"https:\/\/kingscourtyardvumba.com\/index.php\/wp-json\/wp\/v2\/pages\/30\/revisions\/3917"}],"wp:attachment":[{"href":"https:\/\/kingscourtyardvumba.com\/index.php\/wp-json\/wp\/v2\/media?parent=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}